{"id":1637,"date":"2024-04-15T20:50:04","date_gmt":"2024-04-15T18:50:04","guid":{"rendered":"https:\/\/www.blau-weiss-ochtendung.de\/?p=1637"},"modified":"2024-04-15T20:56:33","modified_gmt":"2024-04-15T18:56:33","slug":"kartenvorverkauf-fuer-das-jubilaeumskonzert-gestartet","status":"publish","type":"post","link":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/2024\/04\/15\/kartenvorverkauf-fuer-das-jubilaeumskonzert-gestartet\/","title":{"rendered":"Kartenvorverkauf f\u00fcr das Jubil\u00e4umskonzert gestartet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Es ist soweit! Der Kartenvorverkauf f\u00fcr unser lang erwartetes Jubil\u00e4umskonzert hat begonnen. Unter dem Motto &#8222;<strong>70 Jahre und kein bisschen leise<\/strong>&#8220; feiern wir unser besonderes Jubil\u00e4um.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Konzert findet am <strong>23. November 2024<\/strong> in der <strong>Kulturhalle Ochtendung<\/strong> statt. Nach dem Konzert laden wir Euch herzlich zur After-Show-Party ein, um diesen besonderen Anlass geb\u00fchrend zu feiern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Karten sind zum Preis von <strong>15 \u20ac<\/strong> erh\u00e4ltlich. Ihr k\u00f6nnt die Karten an den folgenden Vorverkaufsstellen erwerben, sowie bei unseren Vereinsmitgliedern.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dingendorf Optik<\/strong>, Michelsbergstra\u00dfe 1 in Ochtendung<\/li>\n\n\n\n<li><strong>Das Lottoeck<\/strong>, Langenbergstra\u00dfe 5 in Ochtendung<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wir freuen uns auf einen unvergesslichen Abend voller Musik! Sichert Euch Eure Karten fr\u00fchzeitig und seid Teil dieses besonderen Ereignisses. Wir sehen uns dort!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"342\" src=\"https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2-1024x342.jpg\" alt=\"\" class=\"wp-image-1642\" srcset=\"https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2-1024x342.jpg 1024w, https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2-300x100.jpg 300w, https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2-768x256.jpg 768w, https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2-1536x512.jpg 1536w, https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2-500x167.jpg 500w, https:\/\/www.blau-weiss-ochtendung.de\/wp-content\/uploads\/2024\/04\/Artikel2.jpg 1607w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Es ist soweit! Der Kartenvorverkauf f\u00fcr unser lang erwartetes Jubil\u00e4umskonzert hat begonnen. Unter dem Motto &#8222;70 Jahre und kein bisschen leise&#8220; feiern wir unser besonderes Jubil\u00e4um. Das Konzert findet am 23. November 2024 in der Kulturhalle Ochtendung statt. Nach dem &hellip; <a href=\"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/2024\/04\/15\/kartenvorverkauf-fuer-das-jubilaeumskonzert-gestartet\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[58,1],"tags":[54,57,56],"class_list":["post-1637","post","type-post","status-publish","format-standard","hentry","category-58","category-veranstaltungen","tag-blau-weiss-ochtendung","tag-jubilaeumskonzert","tag-konzert"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/posts\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":3,"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions"}],"predecessor-version":[{"id":1643,"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions\/1643"}],"wp:attachment":[{"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/media?parent=1637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/categories?post=1637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blau-weiss-ochtendung.de\/index.php\/wp-json\/wp\/v2\/tags?post=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}